{"id":11,"date":"2024-05-03T07:08:22","date_gmt":"2024-05-03T07:08:22","guid":{"rendered":"https:\/\/jurisvisas.com\/?page_id=11"},"modified":"2025-01-28T20:27:24","modified_gmt":"2025-01-28T20:27:24","slug":"home","status":"publish","type":"page","link":"https:\/\/jurisvisas.com\/es\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"11\" class=\"elementor elementor-11\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-578637d e-flex e-con-boxed e-con e-parent\" data-id=\"578637d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a7dd680 e-con-full e-flex e-con e-child\" data-id=\"a7dd680\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19a4d13 elementor-widget elementor-widget-image\" data-id=\"19a4d13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1440\" height=\"807\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/eagle-and-flag-new.webp\" class=\"attachment-full size-full wp-image-4934\" alt=\"eagle and US flag\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/eagle-and-flag-new.webp 1440w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/eagle-and-flag-new-300x168.webp 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/eagle-and-flag-new-1024x574.webp 1024w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/eagle-and-flag-new-768x430.webp 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/eagle-and-flag-new-18x10.webp 18w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76e0910 e-flex e-con-boxed e-con e-child\" data-id=\"76e0910\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d914ccc elementor-widget elementor-widget-image\" data-id=\"d914ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"264\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/ji-logo-for-homepage-e1723825350291.png\" class=\"attachment-full size-full wp-image-2392\" alt=\"\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/ji-logo-for-homepage-e1723825350291.png 1280w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/ji-logo-for-homepage-e1723825350291-300x62.png 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/ji-logo-for-homepage-e1723825350291-1024x211.png 1024w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/ji-logo-for-homepage-e1723825350291-768x158.png 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/ji-logo-for-homepage-e1723825350291-18x4.png 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5752e1 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"e5752e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Juris Immigration<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4652e38 elementor-align-center elementor-tablet-align-center elementor-widget__width-inherit elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"4652e38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/es\/schedule-a-consultation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Programe una consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e5c18f e-flex e-con-boxed e-con e-parent\" data-id=\"7e5c18f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d90a749 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d90a749\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62c97b0 e-flex e-con-boxed e-con e-parent\" data-id=\"62c97b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e6db6fa e-con-full e-flex e-con e-child\" data-id=\"e6db6fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0254362 e-con-full e-flex e-con e-child\" data-id=\"0254362\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0baaaae elementor-widget elementor-widget-heading\" data-id=\"0baaaae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros Servicios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-570f901 e-con-full e-flex e-con e-child\" data-id=\"570f901\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1a086b5 e-flex e-con-boxed e-con e-child\" data-id=\"1a086b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50e8643 custom-height elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"50e8643\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/jurisvisas.com\/es\/eb2-niw\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"841\" height=\"840\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/EB-2-NIW_.jpg\" class=\"attachment-full size-full wp-image-5109\" alt=\"\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/EB-2-NIW_.jpg 841w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/EB-2-NIW_-300x300.jpg 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/EB-2-NIW_-150x150.jpg 150w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/EB-2-NIW_-768x767.jpg 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/EB-2-NIW_-12x12.jpg 12w\" sizes=\"(max-width: 841px) 100vw, 841px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4462f5 e-con-full e-flex e-con e-child\" data-id=\"e4462f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8746ea6 elementor-widget elementor-widget-heading\" data-id=\"8746ea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/es\/eb2-niw\/\">VISA EB-2 NIW<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0ac712 elementor-widget elementor-widget-text-editor\" data-id=\"f0ac712\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"font-size: 14px;\" href=\"https:\/\/jurisvisas.com\/es\/eb2-niw\/\">La Visa EB-2 por Inter\u00e9s Nacional ofrece una v\u00eda r\u00e1pida hacia la residencia permanente en EE.UU.   No se requiere una oferta de empleo ni patrocinio estadounidense.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7688320 e-flex e-con-boxed e-con e-child\" data-id=\"7688320\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f7d5bd custom-height elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6f7d5bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/jurisvisas.com\/es\/investor-visas\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/INVESTOR-VISAS.webp\" class=\"attachment-full size-full wp-image-3597\" alt=\"\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/INVESTOR-VISAS.webp 800w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/INVESTOR-VISAS-300x300.webp 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/INVESTOR-VISAS-150x150.webp 150w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/INVESTOR-VISAS-768x768.webp 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/INVESTOR-VISAS-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6c5cb7 e-con-full e-flex e-con e-child\" data-id=\"a6c5cb7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa3feec elementor-widget elementor-widget-heading\" data-id=\"aa3feec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/es\/investor-visas\/\">INVERSORES<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a168115 elementor-widget elementor-widget-text-editor\" data-id=\"a168115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"font-size: 14px;\" href=\"https:\/\/jurisvisas.com\/es\/investor-visas\/\">Las visas E-2 y EB-5 ofrecen oportunidades ideales para inversores que desean trasladarse a los Estados Unidos.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f56997f e-flex e-con-boxed e-con e-child\" data-id=\"f56997f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-972ca78 custom-height elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"972ca78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/jurisvisas.com\/es\/l-1-visa\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-L1-visa-1.webp\" class=\"attachment-full size-full wp-image-4885\" alt=\"Photo of an architect\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-L1-visa-1.webp 1200w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-L1-visa-1-300x300.webp 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-L1-visa-1-1024x1024.webp 1024w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-L1-visa-1-150x150.webp 150w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-L1-visa-1-768x768.webp 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-L1-visa-1-12x12.webp 12w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7682ec2 e-con-full e-flex e-con e-child\" data-id=\"7682ec2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18ac19f elementor-widget elementor-widget-heading\" data-id=\"18ac19f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/es\/l-1-visa\/\">VISA L-1<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d96fc8 elementor-widget elementor-widget-text-editor\" data-id=\"2d96fc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"font-size: 14px;\" href=\"https:\/\/jurisvisas.com\/es\/l-1-visa\/\">La visa L-1 ofrece la posibilidad de residir y trabajar en los Estados Unidos por per\u00edodos prolongados.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c5a847 e-flex e-con-boxed e-con e-child\" data-id=\"0c5a847\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92e2b96 custom-height elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"92e2b96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/jurisvisas.com\/es\/additional-visa-types\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/Additional-Visa-Types.webp\" class=\"attachment-full size-full wp-image-3612\" alt=\"\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/Additional-Visa-Types.webp 800w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/Additional-Visa-Types-300x300.webp 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/Additional-Visa-Types-150x150.webp 150w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/Additional-Visa-Types-768x768.webp 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2024\/08\/Additional-Visa-Types-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dde6e5f e-con-full e-flex e-con e-child\" data-id=\"dde6e5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1968fa8 elementor-widget elementor-widget-heading\" data-id=\"1968fa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/es\/additional-visa-types\/\">VISAS ADICIONALES<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cfe0b9 elementor-widget elementor-widget-text-editor\" data-id=\"0cfe0b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"font-size: 14px;\" href=\"https:\/\/jurisvisas.com\/es\/additional-visa-types\/\">Dependiendo de sus objetivos, existen visas para vivir y trabajar en los Estados Unidos.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f96ccbd elementor-align-center elementor-tablet-align-center elementor-widget__width-inherit elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-widget elementor-widget-button\" data-id=\"f96ccbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/es\/schedule-a-consultation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Programe una consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57c76af e-flex e-con-boxed e-con e-parent\" data-id=\"57c76af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21949ef elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"21949ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33a4e0f e-flex e-con-boxed e-con e-parent\" data-id=\"33a4e0f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f345f4f e-con-full e-flex e-con e-child\" data-id=\"f345f4f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a93ae9 elementor-widget elementor-widget-heading\" data-id=\"9a93ae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Temas de Inter\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-336c424 e-con-full e-flex e-con e-child\" data-id=\"336c424\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-206a697 e-con-full e-flex e-con e-child\" data-id=\"206a697\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b073a80 custom-height elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b073a80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/jurisvisas.com\/es\/the-impact-of-recent-immigration-policy-changes-on-businesses\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blog-new-administration.webp\" class=\"attachment-full size-full wp-image-4886\" alt=\"\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blog-new-administration.webp 1200w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blog-new-administration-300x300.webp 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blog-new-administration-1024x1024.webp 1024w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blog-new-administration-150x150.webp 150w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blog-new-administration-768x768.webp 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blog-new-administration-12x12.webp 12w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9507af e-con-full e-flex e-con e-child\" data-id=\"e9507af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd07d51 elementor-widget elementor-widget-text-editor\" data-id=\"bd07d51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfQu\u00e9 cambios en la pol\u00edtica migratoria de los EE.UU. se pueden anticipar en el nuevo gobierno de Trump?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71c5a99 e-con-full e-flex e-con e-child\" data-id=\"71c5a99\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3d1657 custom-height elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d3d1657\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/jurisvisas.com\/es\/how-to-avoid-common-immigration-mistakes\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blot-avoid-mistakes.webp\" class=\"attachment-full size-full wp-image-4884\" alt=\"\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blot-avoid-mistakes.webp 1200w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blot-avoid-mistakes-300x300.webp 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blot-avoid-mistakes-1024x1024.webp 1024w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blot-avoid-mistakes-150x150.webp 150w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blot-avoid-mistakes-768x768.webp 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/New-Blot-avoid-mistakes-12x12.webp 12w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f77ff4a e-con-full e-flex e-con e-child\" data-id=\"f77ff4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-349dbac elementor-widget elementor-widget-text-editor\" data-id=\"349dbac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como evitar t\u00edpicos errores de inmigraci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5001098 e-con-full e-flex e-con e-child\" data-id=\"5001098\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e5279f custom-height elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9e5279f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/jurisvisas.com\/es\/how-to-increase-your-chances-of-eb2-niw-approval\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"703\" height=\"574\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/representation-american-flag-us-national-loyalty-day-celebration-1-1.png\" class=\"attachment-full size-full wp-image-5110\" alt=\"US Flag\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/representation-american-flag-us-national-loyalty-day-celebration-1-1.png 703w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/representation-american-flag-us-national-loyalty-day-celebration-1-1-300x245.png 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/representation-american-flag-us-national-loyalty-day-celebration-1-1-15x12.png 15w\" sizes=\"(max-width: 703px) 100vw, 703px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd9cc40 e-con-full e-flex e-con e-child\" data-id=\"cd9cc40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91f750a elementor-widget elementor-widget-text-editor\" data-id=\"91f750a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>C\u00f3mo aumentar las posibilidades de una exitosa aplicaci\u00f3n EB-2 por inter\u00e9s nacional<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5aef2b3 e-flex e-con-boxed e-con e-child\" data-id=\"5aef2b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a83fea custom-height elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3a83fea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/jurisvisas.com\/es\/the-role-of-immigration-in-startups-and-innovation\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/collabo.jpg\" class=\"attachment-full size-full wp-image-5114\" alt=\"immigrants on startups\" srcset=\"https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/collabo.jpg 900w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/collabo-300x200.jpg 300w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/collabo-768x512.jpg 768w, https:\/\/jurisvisas.com\/wp-content\/uploads\/2025\/01\/collabo-18x12.jpg 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-948c53e e-con-full e-flex e-con e-child\" data-id=\"948c53e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1de3005 elementor-widget elementor-widget-text-editor\" data-id=\"1de3005\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El rol de la inmigracion en startups e innovaci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Juris Immigration Schedule Consultation Our Services EB-2 NIW VISA The EB2 NIW visa provides a fast-track to U.S. permanent residency. No employment offer, financial investment or U.S sponsorship are required. INVESTOR VISAS The E-2 visa and the EB-5 visa offer investors ideal opportunities for relocating to the United States. L-1 VISA The L-1 visa makes [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/jurisvisas.com\/es\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jurisvisas.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jurisvisas.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jurisvisas.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jurisvisas.com\/es\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":21,"href":"https:\/\/jurisvisas.com\/es\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":5575,"href":"https:\/\/jurisvisas.com\/es\/wp-json\/wp\/v2\/pages\/11\/revisions\/5575"}],"wp:attachment":[{"href":"https:\/\/jurisvisas.com\/es\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}